{"id":4432,"date":"2024-01-11T16:49:51","date_gmt":"2024-01-11T16:49:51","guid":{"rendered":"https:\/\/ossayasociados.com.co\/web\/?page_id=4432"},"modified":"2024-12-19T13:22:22","modified_gmt":"2024-12-19T13:22:22","slug":"eventos-deportivos","status":"publish","type":"page","link":"https:\/\/ossayasociados.com.co\/web\/eventos-deportivos\/","title":{"rendered":"Eventos Deportivos"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" width=\"564\" height=\"111\" src=\"https:\/\/ossayasociados.com.co\/web\/wp-content\/uploads\/2024\/01\/Logo-Ossa-y-Asociados-1.png\" alt=\"\" srcset=\"https:\/\/ossayasociados.com.co\/web\/wp-content\/uploads\/2024\/01\/Logo-Ossa-y-Asociados-1.png 564w, https:\/\/ossayasociados.com.co\/web\/wp-content\/uploads\/2024\/01\/Logo-Ossa-y-Asociados-1-300x59.png 300w, https:\/\/ossayasociados.com.co\/web\/wp-content\/uploads\/2024\/01\/Logo-Ossa-y-Asociados-1-505x99.png 505w\" sizes=\"(max-width: 564px) 100vw, 564px\" \/><br \/>\n\t\t\t\t\tMen\u00fa<br \/>\n\t\t\t\t\t\t<svg aria-hidden=\"true\"  viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M432 416H16a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16v-32a16 16 0 0 0-16-16zm0-128H16a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16v-32a16 16 0 0 0-16-16zm0-128H16a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16v-32a16 16 0 0 0-16-16zm0-128H16A16 16 0 0 0 0 48v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16V48a16 16 0 0 0-16-16z\"><\/path><\/svg>\t\t\t\t\t<\/p>\n<nav data-toggle-icon=\"&lt;svg aria-hidden=&quot;true&quot; tabindex=&quot;0&quot; class=&quot;e-font-icon-svg e-fas-align-justify&quot; viewBox=&quot;0 0 448 512&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot;&gt;&lt;path d=&quot;M432 416H16a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16v-32a16 16 0 0 0-16-16zm0-128H16a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16v-32a16 16 0 0 0-16-16zm0-128H16a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16v-32a16 16 0 0 0-16-16zm0-128H16A16 16 0 0 0 0 48v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16V48a16 16 0 0 0-16-16z&quot;&gt;&lt;\/path&gt;&lt;\/svg&gt;\" data-close-icon=\"&lt;svg aria-hidden=&quot;true&quot; tabindex=&quot;0&quot; class=&quot;e-font-icon-svg e-far-window-close&quot; viewBox=&quot;0 0 512 512&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot;&gt;&lt;path d=&quot;M464 32H48C21.5 32 0 53.5 0 80v352c0 26.5 21.5 48 48 48h416c26.5 0 48-21.5 48-48V80c0-26.5-21.5-48-48-48zm0 394c0 3.3-2.7 6-6 6H54c-3.3 0-6-2.7-6-6V86c0-3.3 2.7-6 6-6h404c3.3 0 6 2.7 6 6v340zM356.5 194.6L295.1 256l61.4 61.4c4.6 4.6 4.6 12.1 0 16.8l-22.3 22.3c-4.6 4.6-12.1 4.6-16.8 0L256 295.1l-61.4 61.4c-4.6 4.6-12.1 4.6-16.8 0l-22.3-22.3c-4.6-4.6-4.6-12.1 0-16.8l61.4-61.4-61.4-61.4c-4.6-4.6-4.6-12.1 0-16.8l22.3-22.3c4.6-4.6 12.1-4.6 16.8 0l61.4 61.4 61.4-61.4c4.6-4.6 12.1-4.6 16.8 0l22.3 22.3c4.7 4.6 4.7 12.1 0 16.8z&quot;&gt;&lt;\/path&gt;&lt;\/svg&gt;\" data-full-width=\"yes\">\n<ul id=\"menu-1-769d84c\">\n<li id=\"menu-item-3612\"><a href=\"https:\/\/ossayasociados.com.co\/web\/\" class = \"hfe-menu-item\">Home<\/a><\/li>\n<li id=\"menu-item-7869\"><a href=\"https:\/\/ossayasociados.com.co\/web\/experiencias\/\" class = \"hfe-menu-item\">Experiencias<\/a><\/li>\n<li id=\"menu-item-5848\"><a href=\"https:\/\/ossayasociados.com.co\/web\/colombia-vs-chile\/\" class = \"hfe-menu-item\">Eventos<\/a>\n<ul>\n<li id=\"menu-item-6284\"><a href=\"https:\/\/ossayasociados.com.co\/web\/colombia-vs-ecuador\/\" class = \"hfe-sub-menu-item\">Colombia vs Ecuador<\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-4944\"><a href=\"https:\/\/ossayasociados.com.co\/web\/contact\/\" class = \"hfe-menu-item\">Cont\u00e1ctanos<\/a>\n<ul>\n<li id=\"menu-item-5039\"><a href=\"https:\/\/pqr.ossayasociados.com.co\/index.php?a=add&#038;category=5\" class = \"hfe-sub-menu-item\">Hacer solicitud<\/a><\/li>\n<li id=\"menu-item-5038\"><a href=\"https:\/\/pqr.ossayasociados.com.co\/ticket.php\" class = \"hfe-sub-menu-item\">Consultar solicitud<\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-6775\"><a href=\"https:\/\/ossayasociados.com.co\/web\/sostenimiento\/\" class = \"hfe-menu-item\">ODS<\/a><\/li>\n<li id=\"menu-item-7879\"><a href=\"https:\/\/ossayasociados.com.co\/web\/account\/\" class = \"hfe-menu-item\">Cuenta<\/a>\n<ul>\n<li id=\"menu-item-7871\"><a href=\"https:\/\/ossayasociados.com.co\/web\/register\/\" class = \"hfe-sub-menu-item\">Registro<\/a><\/li>\n<li id=\"menu-item-7872\"><a href=\"https:\/\/ossayasociados.com.co\/web\/user\/\" class = \"hfe-sub-menu-item\">Usuario<\/a><\/li>\n<li id=\"menu-item-7874\"><a href=\"https:\/\/ossayasociados.com.co\/web\/login\/\" class = \"hfe-sub-menu-item\">Acceder<\/a><\/li>\n<li id=\"menu-item-7875\"><a href=\"https:\/\/ossayasociados.com.co\/web\/logout\/\" class = \"hfe-sub-menu-item\">Salir<\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-6999\"><a href=\"https:\/\/ossayasociados.com.co\/web\/blog\/\" class = \"hfe-menu-item\">Blog<\/a><\/li>\n<\/ul>\n<\/nav>\n<h2>Eventos Deportivos<\/h2>\n<ul>\n<li>\n\t\t\t\t\t    <a\n\t\t\t\t\t\thref=\"https:\/\/www.facebook.com\/OSSAyAsociadosViajes\" target=\"_blank\" aria-label=\"Facebook\" ><br \/>\n                                                                                                            <\/a>\n                    <\/li>\n<li>\n\t\t\t\t\t    <a\n\t\t\t\t\t\thref=\"https:\/\/www.instagram.com\/ossayasociados\" target=\"_blank\" aria-label=\"Instagram\" ><br \/>\n                                                                                                            <\/a>\n                    <\/li>\n<li>\n\t\t\t\t\t    <a\n\t\t\t\t\t\thref=\"https:\/\/www.linkedin.com\/in\/ossa-y-asociados-05a2a22ab\/\" target=\"_blank\" aria-label=\"LinkedIn\" ><br \/>\n                                                                                                            <\/a>\n                    <\/li>\n<\/ul>\n<p>\t\t\t\t\t\t\t<a href=\"https:\/\/api.whatsapp.com\/send\/?phone=573183706274&#038;text=Hola+buen+d%C3%ADa%2C+solicito+informaci%C3%B3n+sobre&#038;type=phone_number&#038;app_absent=0\" target=\"_blank\" id=\"\"><br \/>\n\t\t\t\t\tContactanos\t\t\t\t<\/a><\/p>\n<ul>\n<li>\n<h1 data-bdt-slideshow-parallax=\"x: 200,-200; opacity: 1,1,0\"  data-reveal=\"reveal-active\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tEVENTOS DEPORTIVOS\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h1>\n<p>En Ossa y Asociados, te ofrecemos una lista actualizada de los mejores eventos deportivos. Revisa la disponibilidad y asegura tu entrada para disfrutar del deporte en vivo de manera r\u00e1pida y sencilla.<\/p>\n<p>\t\t\t<a href=\"https:\/\/ossayasociados.com.co\/web\/colombia-vs-chile\/\"><br \/>\n\t\t\t\t\tObtenga Informaci\u00f3n<br \/>\n\t\t\t<\/a>\n\t\t<\/li>\n<li>\n<h4 data-bdt-slideshow-parallax=\"x: 100,-100; opacity: 1,1,0\" data-reveal=\"reveal-active\">\n                            Eventos futbol                        <\/h4>\n<h1 data-bdt-slideshow-parallax=\"x: 200,-200; opacity: 1,1,0\"  data-reveal=\"reveal-active\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tColombia Vs CHILE\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h1>\n<p>Consulta nuestra secci\u00f3n de eventos para ver todos los detalles del pr\u00f3ximo partido de nuestra Selecci\u00f3n en las eliminatorias. Asegura tus entradas y \u00fanete a la emoci\u00f3n en el estadio apoyando a Colombia.<\/p>\n<p>\t\t\t<a href=\"https:\/\/ossayasociados.com.co\/web\/colombia-vs-chile\/\"><br \/>\n\t\t\t\t\tVer M\u00e1s<br \/>\n\t\t\t<\/a>\n\t\t<\/li>\n<li>\n<h1 data-bdt-slideshow-parallax=\"x: 200,-200; opacity: 1,1,0\"  data-reveal=\"reveal-active\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tcolombia Vs ecuador \t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h1>\n<p>Encuentra toda la informaci\u00f3n sobre el pr\u00f3ximo partido en la secci\u00f3n de eventos. Compra tus entradas y vive la experiencia de apoyar a Colombia en vivo desde el estadio.<\/p>\n<p>\t\t\t<a href=\"https:\/\/ossayasociados.com.co\/web\/colombia-vs-ecuador\/\"><br \/>\n\t\t\t\t\tVer M\u00e1s<br \/>\n\t\t\t<\/a>\n\t\t<\/li>\n<\/ul>\n<ul>\n<li bdt-slideshow-item=\"0\" data-label=\"01\" ><a href=\"#\"><\/a><\/li>\n<li bdt-slideshow-item=\"1\" data-label=\"02\" ><a href=\"#\"><\/a><\/li>\n<li bdt-slideshow-item=\"2\" data-label=\"03\" ><a href=\"#\"><\/a><\/li>\n<\/ul>\n<p>\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/OSSAyAsociadosViajes\" target=\"_blank\"><br \/>\n\t\t\t\t\t\t\t\t\tFacebook<br \/>\n\t\t\t\t\t\t\t<\/a><br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/api.whatsapp.com\/send\/?phone=573183706274&#038;text=Hola+buen+d%C3%ADa%2C+solicito+informaci%C3%B3n+sobre&#038;type=phone_number&#038;app_absent=0\" target=\"_blank\"><br \/>\n\t\t\t\t\t\t\t\t\tWhatsApp<br \/>\n\t\t\t\t\t\t\t<\/a><br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/ossayasociados\" target=\"_blank\"><br \/>\n\t\t\t\t\t\t\t\t\tInstagram<br \/>\n\t\t\t\t\t\t\t<\/a><\/p>\n<h1>Valor real para ti<\/h1>\n<h3>\n                        Acceso Exclusivo<br \/>\n                    <\/h3>\n<p>                        Disfruta de entradas a los eventos deportivos m\u00e1s relevantes, con opciones VIP y experiencias \u00fanicas.<\/p>\n<h3>\n                        Paquetes Personalizados<br \/>\n                    <\/h3>\n<p>                        Dise\u00f1amos tu experiencia deportiva seg\u00fan tus preferencias, incluyendo transporte, alojamiento y actividades adicionales.                    <\/p>\n<h3>\n                        Asesor\u00eda Experta<br \/>\n                    <\/h3>\n<p>                        Nuestro equipo ofrece asistencia integral, desde la compra de entradas hasta recomendaciones de viaje.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Men\u00fa Home Experiencias Eventos Colombia vs Ecuador Cont\u00e1ctanos Hacer solicitud Consultar solicitud ODS Cuenta Registro Usuario Acceder Salir Blog Eventos Deportivos Contactanos EVENTOS DEPORTIVOS En Ossa y Asociados, te ofrecemos una lista actualizada de los mejores eventos deportivos. Revisa la disponibilidad y asegura tu entrada para disfrutar del deporte en vivo de manera r\u00e1pida y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-4432","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eventos Deportivos - Ossa y Asociados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ossayasociados.com.co\/web\/eventos-deportivos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eventos Deportivos - Ossa y Asociados\" \/>\n<meta property=\"og:description\" content=\"Men\u00fa Home Experiencias Eventos Colombia vs Ecuador Cont\u00e1ctanos Hacer solicitud Consultar solicitud ODS Cuenta Registro Usuario Acceder Salir Blog Eventos Deportivos Contactanos EVENTOS DEPORTIVOS En Ossa y Asociados, te ofrecemos una lista actualizada de los mejores eventos deportivos. Revisa la disponibilidad y asegura tu entrada para disfrutar del deporte en vivo de manera r\u00e1pida y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ossayasociados.com.co\/web\/eventos-deportivos\/\" \/>\n<meta property=\"og:site_name\" content=\"Ossa y Asociados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OSSAyAsociadosViajes\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-19T13:22:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ossayasociados.com.co\/web\/wp-content\/uploads\/2024\/01\/Logo-Ossa-y-Asociados-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ossayasociados.com.co\\\/web\\\/eventos-deportivos\\\/\",\"url\":\"https:\\\/\\\/ossayasociados.com.co\\\/web\\\/eventos-deportivos\\\/\",\"name\":\"Eventos Deportivos - Ossa y Asociados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ossayasociados.com.co\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ossayasociados.com.co\\\/web\\\/eventos-deportivos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ossayasociados.com.co\\\/web\\\/eventos-deportivos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ossayasociados.com.co\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-Ossa-y-Asociados-1.png\",\"datePublished\":\"2024-01-11T16:49:51+00:00\",\"dateModified\":\"2024-12-19T13:22:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ossayasociados.com.co\\\/web\\\/eventos-deportivos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ossayasociados.com.co\\\/web\\\/eventos-deportivos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ossayasociados.com.co\\\/web\\\/eventos-deportivos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ossayasociados.com.co\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-Ossa-y-Asociados-1.png\",\"contentUrl\":\"https:\\\/\\\/ossayasociados.com.co\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-Ossa-y-Asociados-1.png\",\"width\":564,\"height\":111},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ossayasociados.com.co\\\/web\\\/eventos-deportivos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ossayasociados.com.co\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos Deportivos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ossayasociados.com.co\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/ossayasociados.com.co\\\/web\\\/\",\"name\":\"Ossa y Asociados\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ossayasociados.com.co\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ossayasociados.com.co\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ossayasociados.com.co\\\/web\\\/#organization\",\"name\":\"Ossa y Asociados\",\"url\":\"https:\\\/\\\/ossayasociados.com.co\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ossayasociados.com.co\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ossayasociados.com.co\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/LOGO-CON-LA-O-8.png\",\"contentUrl\":\"https:\\\/\\\/ossayasociados.com.co\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/LOGO-CON-LA-O-8.png\",\"width\":1080,\"height\":1920,\"caption\":\"Ossa y Asociados\"},\"image\":{\"@id\":\"https:\\\/\\\/ossayasociados.com.co\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OSSAyAsociadosViajes\",\"https:\\\/\\\/www.instagram.com\\\/ossayasociados?igsh=ZmpweHA4dG9za2Rm\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eventos Deportivos - Ossa y Asociados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ossayasociados.com.co\/web\/eventos-deportivos\/","og_locale":"es_ES","og_type":"article","og_title":"Eventos Deportivos - Ossa y Asociados","og_description":"Men\u00fa Home Experiencias Eventos Colombia vs Ecuador Cont\u00e1ctanos Hacer solicitud Consultar solicitud ODS Cuenta Registro Usuario Acceder Salir Blog Eventos Deportivos Contactanos EVENTOS DEPORTIVOS En Ossa y Asociados, te ofrecemos una lista actualizada de los mejores eventos deportivos. Revisa la disponibilidad y asegura tu entrada para disfrutar del deporte en vivo de manera r\u00e1pida y [&hellip;]","og_url":"https:\/\/ossayasociados.com.co\/web\/eventos-deportivos\/","og_site_name":"Ossa y Asociados","article_publisher":"https:\/\/www.facebook.com\/OSSAyAsociadosViajes","article_modified_time":"2024-12-19T13:22:22+00:00","og_image":[{"url":"https:\/\/ossayasociados.com.co\/web\/wp-content\/uploads\/2024\/01\/Logo-Ossa-y-Asociados-1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ossayasociados.com.co\/web\/eventos-deportivos\/","url":"https:\/\/ossayasociados.com.co\/web\/eventos-deportivos\/","name":"Eventos Deportivos - Ossa y Asociados","isPartOf":{"@id":"https:\/\/ossayasociados.com.co\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ossayasociados.com.co\/web\/eventos-deportivos\/#primaryimage"},"image":{"@id":"https:\/\/ossayasociados.com.co\/web\/eventos-deportivos\/#primaryimage"},"thumbnailUrl":"https:\/\/ossayasociados.com.co\/web\/wp-content\/uploads\/2024\/01\/Logo-Ossa-y-Asociados-1.png","datePublished":"2024-01-11T16:49:51+00:00","dateModified":"2024-12-19T13:22:22+00:00","breadcrumb":{"@id":"https:\/\/ossayasociados.com.co\/web\/eventos-deportivos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ossayasociados.com.co\/web\/eventos-deportivos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ossayasociados.com.co\/web\/eventos-deportivos\/#primaryimage","url":"https:\/\/ossayasociados.com.co\/web\/wp-content\/uploads\/2024\/01\/Logo-Ossa-y-Asociados-1.png","contentUrl":"https:\/\/ossayasociados.com.co\/web\/wp-content\/uploads\/2024\/01\/Logo-Ossa-y-Asociados-1.png","width":564,"height":111},{"@type":"BreadcrumbList","@id":"https:\/\/ossayasociados.com.co\/web\/eventos-deportivos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ossayasociados.com.co\/web\/"},{"@type":"ListItem","position":2,"name":"Eventos Deportivos"}]},{"@type":"WebSite","@id":"https:\/\/ossayasociados.com.co\/web\/#website","url":"https:\/\/ossayasociados.com.co\/web\/","name":"Ossa y Asociados","description":"","publisher":{"@id":"https:\/\/ossayasociados.com.co\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ossayasociados.com.co\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ossayasociados.com.co\/web\/#organization","name":"Ossa y Asociados","url":"https:\/\/ossayasociados.com.co\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ossayasociados.com.co\/web\/#\/schema\/logo\/image\/","url":"https:\/\/ossayasociados.com.co\/web\/wp-content\/uploads\/2025\/07\/LOGO-CON-LA-O-8.png","contentUrl":"https:\/\/ossayasociados.com.co\/web\/wp-content\/uploads\/2025\/07\/LOGO-CON-LA-O-8.png","width":1080,"height":1920,"caption":"Ossa y Asociados"},"image":{"@id":"https:\/\/ossayasociados.com.co\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OSSAyAsociadosViajes","https:\/\/www.instagram.com\/ossayasociados?igsh=ZmpweHA4dG9za2Rm"]}]}},"_links":{"self":[{"href":"https:\/\/ossayasociados.com.co\/web\/wp-json\/wp\/v2\/pages\/4432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ossayasociados.com.co\/web\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ossayasociados.com.co\/web\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ossayasociados.com.co\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ossayasociados.com.co\/web\/wp-json\/wp\/v2\/comments?post=4432"}],"version-history":[{"count":94,"href":"https:\/\/ossayasociados.com.co\/web\/wp-json\/wp\/v2\/pages\/4432\/revisions"}],"predecessor-version":[{"id":8033,"href":"https:\/\/ossayasociados.com.co\/web\/wp-json\/wp\/v2\/pages\/4432\/revisions\/8033"}],"wp:attachment":[{"href":"https:\/\/ossayasociados.com.co\/web\/wp-json\/wp\/v2\/media?parent=4432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}